{"id":1576141,"date":"2025-09-10T15:32:02","date_gmt":"2025-09-10T15:32:02","guid":{"rendered":"https:\/\/deqori.eu\/?post_type=product&#038;p=1576141"},"modified":"2025-10-31T09:46:51","modified_gmt":"2025-10-31T09:46:51","slug":"alu-dibond-bild-farbenfroher-hafen","status":"publish","type":"product","link":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/","title":{"rendered":"Alu-Dibond Bild &#8211; Farbenfroher Hafen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1452802\" class=\"elementor elementor-1452802\" data-elementor-gstype=\"generic\" data-page-el-selector=\"body.elementor-page-1452802\" data-disable-padding=\"\">\n\t\t\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-top-section elementor-element elementor-element-0010174 rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0010174\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0d3d6fd elementor-hidden-mobile\" data-id=\"0d3d6fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--0d3d6fd elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-beca296\" data-id=\"beca296\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--beca296 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ccf0b1 elementor-widget elementor-widget-heading\" data-id=\"3ccf0b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Alu-Dibond Bild mit UV-Motivdruck<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8465dc0 elementor-widget elementor-widget-heading\" data-id=\"8465dc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Modern, robust<br> &amp; stilvoll<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-958d825 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"958d825\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hochwertiger UV-Direktdruck<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Robuste Alu-Dibond Platte <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sofort Montagefertig <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b744611 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b744611\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c3392fb rey-colbg--classic\" data-id=\"c3392fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--c3392fb elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f877851 elementor-widget elementor-widget-image\" data-id=\"f877851\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/07\/Multi-AD-top-view.jpg\" class=\"attachment-full size-full wp-image-1688721\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3613c81\" data-id=\"3613c81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--3613c81 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfea92e elementor-widget elementor-widget-text-editor\" data-id=\"bfea92e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Moderne Eleganz \u2013 das Alu-Dibond Wandbild mit UV-Druck<\/h2><p>Ein Bild an der Wand ist mehr als blo\u00dfe Dekoration \u2013 es beeinflusst die gesamte Wirkung eines Raumes, bringt Stimmung, Helligkeit und Tiefe und verleiht deinem Zuhause eine pers\u00f6nliche Note. Mit dem Alu-Dibond Bild &#8211; Farbenfroher Hafen von DEQORI entscheidest du dich f\u00fcr ein Wandbild, das modernes Design mit langlebiger Qualit\u00e4t verbindet. Die geb\u00fcrstete Aluminiumoberfl\u00e4che verleiht dem Motiv eine elegante Struktur, die je nach Lichteinfall subtil schimmert und dem Bild eine besondere Dimension verleiht. Der hochwertige UV-Direktdruck sorgt f\u00fcr kr\u00e4ftige Farben, gestochen scharfe Details und eine klare Darstellung, die auch aus der N\u00e4he \u00fcberzeugt. Das Resultat ist ein Kunstwerk, das durch seine Brillanz und Ausdruckskraft begeistert \u2013 nicht nur am Tag des Aufh\u00e4ngens, sondern \u00fcber viele Jahre hinweg. Ob als eleganter Akzent im Wohnzimmer, als modernes Statement im Schlafzimmer, als stilvolle Erg\u00e4nzung im B\u00fcro oder als Hingucker im Flur \u2013 das Wandbild f\u00fcgt sich harmonisch in verschiedene Einrichtungsstile ein und sorgt f\u00fcr eine Atmosph\u00e4re, die sowohl zeitlos als auch modern wirkt.<\/p><h2 style=\"font-size: 1em; margin-bottom: 3px;\">Hochwertiger UV-Druck \u2013 detailreich &amp; langlebig<\/h2><p>Die Wirkung eines Wandbildes h\u00e4ngt entscheidend von der Pr\u00e4zision und Farbbrillanz des Drucks ab. Beim Alu-Dibond Bild &#8211; Farbenfroher Hafen wird das Motiv mit modernster UV-Drucktechnologie direkt auf die geb\u00fcrstete Aluminiumoberfl\u00e4che aufgebracht. Durch diese Technik entstehen satte Farben, kontrastreiche \u00dcberg\u00e4nge und feinste Details, die lange erhalten bleiben. Die metallische Struktur der Oberfl\u00e4che verst\u00e4rkt die Tiefenwirkung des Motivs zus\u00e4tzlich und verleiht dem Bild eine besondere Exklusivit\u00e4t. Doch nicht nur optisch \u00fcberzeugt das Wandbild: Es ist kratzfest, formstabil und feuchtigkeitsresistent, sodass es auch im Alltag seine Qualit\u00e4t beh\u00e4lt. Die robuste Oberfl\u00e4che l\u00e4sst sich leicht reinigen und bleibt selbst bei h\u00e4ufiger Pflege farbintensiv und brillant. Dadurch eignet sich das Bild nicht nur f\u00fcr klassische Wohnbereiche, sondern auch f\u00fcr st\u00e4rker beanspruchte R\u00e4ume wie K\u00fcchen oder B\u00e4der sowie f\u00fcr \u00fcberdachte Au\u00dfenbereiche wie Balkone oder Terrassen. So wird aus dem Wandbild ein vielseitiges Kunstobjekt, das sowohl drinnen als auch drau\u00dfen seine Wirkung entfaltet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-inner-section elementor-element elementor-element-1317c13 rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1317c13\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1988316 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"1988316\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--1988316 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae3ddd4 elementor-widget elementor-widget-image\" data-id=\"ae3ddd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/03\/stars.svg\" class=\"attachment-full size-full wp-image-1449717\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-99cb245\" data-id=\"99cb245\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--99cb245 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9c94fb elementor-widget elementor-widget-heading\" data-id=\"e9c94fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Deine Vorteile<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6070322 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6070322\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 Tage R\u00fcckgaberecht<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ab 50 \u20ac versandkostenfrei in DE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">sicher einkaufen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">umweltbewusste Produktion<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Individualdruck m\u00f6glich<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c34ccf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c34ccf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c7894c\" data-id=\"7c7894c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--7c7894c elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-281be21 elementor-widget elementor-widget-text-editor\" data-id=\"281be21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Alltagstauglich &amp; unkompliziert \u2013 Kunst ohne Aufwand<\/h2><p>Ein sch\u00f6nes Bild soll nicht nur \u00e4sthetisch beeindrucken, sondern auch im Alltag praktisch sein \u2013 und genau daf\u00fcr ist das Alu-Dibond Bild &#8211; Farbenfroher Hafen geschaffen. Die Alu-Dibond Platte ist stabil, gleichzeitig aber angenehm leicht, was Transport und Anbringung erheblich erleichtert. Das Material bleibt auch bei Temperaturschwankungen formstabil und beh\u00e4lt seine klare Optik. Die Pflege ist unkompliziert: Staub entfernst du mit einem trockenen Tuch, leichte Verschmutzungen lassen sich problemlos mit einem feuchten Tuch abwischen \u2013 ganz ohne aggressive Reinigungsmittel. Dank der widerstandsf\u00e4higen Oberfl\u00e4che bleibt das Motiv auch nach Jahren klar, farbintensiv und brillant, selbst in lebhaften Haushalten oder stark genutzten R\u00e4umen. Diese Kombination aus Langlebigkeit, einfacher Pflege und stilvollem Design macht das Wandbild zu einem Begleiter, an dem du dich Tag f\u00fcr Tag erfreuen kannst. Kunst ohne Aufwand \u2013 daf\u00fcr steht dieses DEQORI Wandbild, das Eleganz und Alltag auf ideale Weise verbindet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-top-section elementor-element elementor-element-fdc69ef rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdc69ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b8fe25 elementor-hidden-mobile\" data-id=\"7b8fe25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--7b8fe25 elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9cd8ce3\" data-id=\"9cd8ce3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--9cd8ce3 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46599b4 elementor-widget elementor-widget-heading\" data-id=\"46599b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kunst auf<br>Aluminium<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c1577c elementor-widget elementor-widget-heading\" data-id=\"3c1577c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pflegeleicht im Alltag, eindrucksvoll an der Wand<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a37b644 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a37b644\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ca5080\" data-id=\"1ca5080\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--1ca5080 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f819888 elementor-widget elementor-widget-text-editor\" data-id=\"f819888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Einfache Montage \u2013 stilvoll gel\u00f6st<\/h2><p>Damit du dein neues Wandbild sofort genie\u00dfen kannst, ist es bereits mit einem vormontierten Aufh\u00e4ngesystem ausgestattet. Du musst es lediglich an einem Haken oder einer Schraube befestigen \u2013 schnell, sicher und ohne komplizierte Vorbereitung. Durch die verdeckte Halterung entsteht ein moderner Schwebe-Effekt, bei dem das Bild leicht vor der Wand zu schweben scheint. Dieser Effekt verleiht dem Motiv zus\u00e4tzliche Leichtigkeit und unterstreicht die hochwertige Wirkung des Materials. Ob als einzelnes Kunstwerk, das den Blick auf sich zieht, oder als Teil einer kreativen Bilderwand mit verschiedenen Formaten \u2013 das Alu-Dibond Bild &#8211; Farbenfroher Hafen l\u00e4sst sich flexibel kombinieren und an deinen Einrichtungsstil anpassen. So verleiht es jedem Raum Charakter, Individualit\u00e4t und eine elegante Note, die lange begeistert.<\/p><h2 style=\"font-size: 1em; margin-bottom: 3px;\">Lieferumfang:<\/h2><p>1x Alu-Dibond Wandbild<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-1122288 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1122288\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d7c08ed rey-colbg--classic\" data-id=\"d7c08ed\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--d7c08ed elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5081cd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5081cd1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fe86d43\" data-id=\"fe86d43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--fe86d43 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f136dcb elementor-widget elementor-widget-image\" data-id=\"f136dcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/11\/instructions-icon.svg\" class=\"attachment-full size-full wp-image-1448531\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-893def0\" data-id=\"893def0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--893def0 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b394a59 elementor-widget elementor-widget-heading\" data-id=\"b394a59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anleitung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efe8f1a u-last-p-margin elementor-widget elementor-widget-text-editor\" data-id=\"efe8f1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tBen\u00f6tigst du Unterst\u00fctzung beim Aufbau? Kein Problem! Wirf gerne einen Blick in die Montageanleitung und Pflegehinweise.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-703de65 elementor-button-underline elementor-widget elementor-widget-button\" data-id=\"703de65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/static-imageserver.b-cdn.net\/INSTRUCTIONS\/DEQORI-AD-Instructions.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anleitung &amp; Sicherheitshinweise<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78659fc rey-colbg--classic\" data-id=\"78659fc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--78659fc elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b71fc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b71fc8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ddc1b7d\" data-id=\"ddc1b7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--ddc1b7d elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77c437c elementor-widget elementor-widget-image\" data-id=\"77c437c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/11\/info-icon.svg\" class=\"attachment-full size-full wp-image-1448527\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2004291\" data-id=\"2004291\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--2004291 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76e5f44 elementor-widget elementor-widget-heading\" data-id=\"76e5f44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hinweis<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da733b1 u-last-p-margin elementor-widget elementor-widget-text-editor\" data-id=\"da733b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tJedes Produkt ist ein Unikat und wird, sofern nicht anders angegeben, individuell f\u00fcr dich gefertigt, wodurch h\u00f6here Lieferzeiten entstehen k\u00f6nnen. Au\u00dferdem k\u00f6nnen Farbabweichungen je nach Monitor und Endger\u00e4t auftreten, speziell bei Motiven mit nachgeahmten Materialien.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"[rey_global_section id=\"1452854\"]\n","protected":false},"featured_media":1576143,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[19,17285],"product_tag":[17453,17455,17454,584,8991,18045,3787,18047,18046,906,632,11528,665,587,588],"class_list":{"0":"post-1576141","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wandbilder-glasbilder","7":"product_cat-aludibond","8":"product_tag-alu-dibond","9":"product_tag-alu-verbundplatte","10":"product_tag-aluverbund","11":"product_tag-bild","12":"product_tag-bunte-boote","13":"product_tag-farbenfroher-hafen","14":"product_tag-foto","15":"product_tag-hafenszene","16":"product_tag-mediterraner-hafen","17":"product_tag-metall","18":"product_tag-modern","19":"product_tag-outdoor","20":"product_tag-platte","21":"product_tag-wandbild","22":"product_tag-wanddeko","23":"pa_farbe-mehrfarbig","24":"pa_format-form-quadratisch","25":"pa_format-form-horizontal","26":"pa_pid-18044","27":"pa_stil-themen-strand-meer","28":"pa_stil-themen-kunst-malerei","29":"pa_zimmer-wohnzimmer","30":"pa_zimmer-kueche-esszimmer","31":"pa_zimmer-flur-eingangsbereich","32":"pa_zimmer-arbeitszimmer","33":"fpd-variation-needed","35":"first","36":"instock","37":"sale","38":"taxable","39":"shipping-taxable","40":"purchasable","41":"product-type-variable","swatches":"rey-swatches","show_selected":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aluminium Wandbild Farbenfroher Hafen \u2013 Strand &amp; Meer | DEQORI<\/title>\n<meta name=\"description\" content=\"Farbenfroher Hafen als Aluminium Wandbild \u2013 individuelle Gr\u00f6\u00dfe &amp; Druck. Bringen Sie maritimes Flair nach Hause! Jetzt bei DEQORI entdecken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminium Wandbild Farbenfroher Hafen \u2013 Strand &amp; Meer | DEQORI\" \/>\n<meta property=\"og:description\" content=\"Farbenfroher Hafen als Aluminium Wandbild \u2013 individuelle Gr\u00f6\u00dfe &amp; Druck. Bringen Sie maritimes Flair nach Hause! Jetzt bei DEQORI entdecken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/\" \/>\n<meta property=\"og:site_name\" content=\"DEQORI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/deqorishop\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T09:46:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-AD-30-30-S-5350-UV.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/aludibond\\\/alu-dibond-bild-farbenfroher-hafen\\\/\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/aludibond\\\/alu-dibond-bild-farbenfroher-hafen\\\/\",\"name\":\"Aluminium Wandbild Farbenfroher Hafen \u2013 Strand & Meer | DEQORI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/aludibond\\\/alu-dibond-bild-farbenfroher-hafen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/aludibond\\\/alu-dibond-bild-farbenfroher-hafen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1-AD-30-30-S-5350-UV.jpg\",\"datePublished\":\"2025-09-10T15:32:02+00:00\",\"dateModified\":\"2025-10-31T09:46:51+00:00\",\"description\":\"Farbenfroher Hafen als Aluminium Wandbild \u2013 individuelle Gr\u00f6\u00dfe & Druck. Bringen Sie maritimes Flair nach Hause! Jetzt bei DEQORI entdecken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/aludibond\\\/alu-dibond-bild-farbenfroher-hafen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/aludibond\\\/alu-dibond-bild-farbenfroher-hafen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/aludibond\\\/alu-dibond-bild-farbenfroher-hafen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1-AD-30-30-S-5350-UV.jpg\",\"contentUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1-AD-30-30-S-5350-UV.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/aludibond\\\/alu-dibond-bild-farbenfroher-hafen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alu-Dibond Bild &#8211; Farbenfroher Hafen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\",\"name\":\"DEQORI\",\"description\":\"MOTIV-ierte Wandkunst f\u00fcr deine Wohnf\u00fchloase\",\"publisher\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deqori.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#organization\",\"name\":\"DEQORI\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/deqori-logo-500px-blau-v3.png\",\"contentUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/deqori-logo-500px-blau-v3.png\",\"width\":500,\"height\":130,\"caption\":\"DEQORI\"},\"image\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/deqorishop\\\/\",\"https:\\\/\\\/www.instagram.com\\\/deqorishop\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/deqorishop\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/deqori.eu\\\/de\\\/widerruf\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"DEQORI\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"AD-5350-UV\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aluminium Wandbild Farbenfroher Hafen \u2013 Strand & Meer | DEQORI","description":"Farbenfroher Hafen als Aluminium Wandbild \u2013 individuelle Gr\u00f6\u00dfe & Druck. Bringen Sie maritimes Flair nach Hause! Jetzt bei DEQORI entdecken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/","og_locale":"de_DE","og_type":"article","og_title":"Aluminium Wandbild Farbenfroher Hafen \u2013 Strand & Meer | DEQORI","og_description":"Farbenfroher Hafen als Aluminium Wandbild \u2013 individuelle Gr\u00f6\u00dfe & Druck. Bringen Sie maritimes Flair nach Hause! Jetzt bei DEQORI entdecken.","og_url":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/","og_site_name":"DEQORI","article_publisher":"https:\/\/www.facebook.com\/deqorishop\/","article_modified_time":"2025-10-31T09:46:51+00:00","og_image":[{"url":"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-AD-30-30-S-5350-UV.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/","url":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/","name":"Aluminium Wandbild Farbenfroher Hafen \u2013 Strand & Meer | DEQORI","isPartOf":{"@id":"https:\/\/deqori.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/#primaryimage"},"image":{"@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/#primaryimage"},"thumbnailUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-AD-30-30-S-5350-UV.jpg","datePublished":"2025-09-10T15:32:02+00:00","dateModified":"2025-10-31T09:46:51+00:00","description":"Farbenfroher Hafen als Aluminium Wandbild \u2013 individuelle Gr\u00f6\u00dfe & Druck. Bringen Sie maritimes Flair nach Hause! Jetzt bei DEQORI entdecken.","breadcrumb":{"@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/#primaryimage","url":"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-AD-30-30-S-5350-UV.jpg","contentUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-AD-30-30-S-5350-UV.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/aludibond\/alu-dibond-bild-farbenfroher-hafen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/deqori.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/deqori.eu\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Alu-Dibond Bild &#8211; Farbenfroher Hafen"}]},{"@type":"WebSite","@id":"https:\/\/deqori.eu\/de\/#website","url":"https:\/\/deqori.eu\/de\/","name":"DEQORI","description":"MOTIV-ierte Wandkunst f\u00fcr deine Wohnf\u00fchloase","publisher":{"@id":"https:\/\/deqori.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deqori.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/deqori.eu\/de\/#organization","name":"DEQORI","url":"https:\/\/deqori.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/deqori.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/03\/deqori-logo-500px-blau-v3.png","contentUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/03\/deqori-logo-500px-blau-v3.png","width":500,"height":130,"caption":"DEQORI"},"image":{"@id":"https:\/\/deqori.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/deqorishop\/","https:\/\/www.instagram.com\/deqorishop\/","https:\/\/www.pinterest.com\/deqorishop\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/deqori.eu\/de\/widerruf\/"}}]},"product_brand":"DEQORI","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"AD-5350-UV","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product\/1576141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/comments?post=1576141"}],"version-history":[{"count":0,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product\/1576141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/media\/1576143"}],"wp:attachment":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/media?parent=1576141"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_brand?post=1576141"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_cat?post=1576141"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_tag?post=1576141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}