{"id":1731420,"date":"2025-09-14T02:24:02","date_gmt":"2025-09-14T02:24:02","guid":{"rendered":"https:\/\/deqori.eu\/?post_type=product&#038;p=1731420"},"modified":"2025-10-31T22:39:50","modified_gmt":"2025-10-31T22:39:50","slug":"led-bild-lampe-gebuersteter-stahl","status":"publish","type":"product","link":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/","title":{"rendered":"LED-Bild\/-Lampe &#8211; Geb\u00fcrsteter Stahl"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1452812\" class=\"elementor elementor-1452812\" data-elementor-gstype=\"generic\" data-page-el-selector=\"body.elementor-page-1452812\" data-disable-padding=\"\">\n\t\t\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-top-section elementor-element elementor-element-7877853 rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7877853\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aed24e3 elementor-hidden-mobile\" data-id=\"aed24e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--aed24e3 elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-58f3211\" data-id=\"58f3211\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--58f3211 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d68b8e4 elementor-widget elementor-widget-heading\" data-id=\"d68b8e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">LED-Wandbild mit UV-Druck<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46d3179 elementor-widget elementor-widget-heading\" data-id=\"46d3179\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kunst &amp; Licht<br>im Einklang<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71b2edc elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"71b2edc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hochwertiger UV-Direktdruck<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gleichm\u00e4\u00dfig beleuchtet<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sofort aufh\u00e4ngbar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-823fcda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"823fcda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79c423b rey-colbg--classic\" data-id=\"79c423b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--79c423b elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c8f1cc elementor-widget elementor-widget-image\" data-id=\"9c8f1cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/07\/Multi-LW-top-view.jpg\" class=\"attachment-full size-full wp-image-1688294\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b96aa0b\" data-id=\"b96aa0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--b96aa0b elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02b5f24 elementor-widget elementor-widget-text-editor\" data-id=\"02b5f24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Stil zum Aufh\u00e4ngen \u2013 Design, das Eindruck macht<\/h2><p>Ein Wandbild kann weit mehr, als nur leere Fl\u00e4chen zu f\u00fcllen \u2013 es ver\u00e4ndert die Atmosph\u00e4re eines Raumes, bringt Struktur an die Wand und sorgt f\u00fcr ein stimmiges Gesamtbild. Genau daf\u00fcr wurde das LED-Bild\/-Lampe &#8211; Geb\u00fcrsteter Stahl von DEQORI geschaffen. Mit seiner schlanken Tiefe von nur 3,8 cm wirkt es modern, elegant und gleichzeitig hochwertig. Der Rahmen \u2013 wahlweise in klassischem Wei\u00df oder edlem Schwarz \u2013 f\u00fcgt sich harmonisch in verschiedenste Einrichtungsstile ein, ohne dabei aufdringlich zu wirken. Klare Linien und ein reduziertes Design machen es zum idealen Begleiter f\u00fcr minimalistische R\u00e4ume ebenso wie f\u00fcr gem\u00fctlich eingerichtete Wohnbereiche. Ob im Flur, Wohnzimmer oder Homeoffice \u2013 dieses LED-Wandbild bringt sofort mehr Ruhe, Stil und Harmonie in Ihre vier W\u00e4nde. Und das Beste: Es \u00fcberzeugt nicht nur optisch, sondern auch durch seine hochwertige Verarbeitung. Ein echter Blickfang mit zur\u00fcckhaltender Eleganz.<\/p><h2 style=\"font-size: 1em; margin-bottom: 3px;\">Licht zum Wohlf\u00fchlen \u2013 dekorativ und funktional zugleich<\/h2><p>Was das LED-Bild\/-Lampe &#8211; Geb\u00fcrsteter Stahl besonders macht, ist seine integrierte LED-Beleuchtung. Sie sorgt f\u00fcr eine angenehme, gleichm\u00e4\u00dfige Lichtstimmung \u2013 unaufdringlich, aber wirkungsvoll. Das neutralwei\u00dfe Licht (4000 K) leuchtet flimmerfrei und weich und schafft genau die richtige Atmosph\u00e4re f\u00fcr entspannte Abende, gem\u00fctliche Stunden oder einfach als stilvolle Erg\u00e4nzung im Alltag. Der integrierte Diffusor sorgt daf\u00fcr, dass sich das Licht weich und gleichm\u00e4\u00dfig \u00fcber die gesamte Fl\u00e4che verteilt, wodurch das Wandbild den Eindruck erweckt, von innen heraus zu leuchten. So entsteht eine stimmungsvolle Beleuchtung, die nicht nur angenehm wirkt, sondern zugleich energieeffizient ist. Ob als stimmungsvolle Lichtquelle am Abend oder dezentes Ambientelicht tags\u00fcber \u2013 das LED-Bild\/-Lampe &#8211; Geb\u00fcrsteter Stahl beleuchtet dein Zuhause mit Stil und Substanz. Besonders in dunkleren Raumbereichen entfaltet es seine volle Wirkung und sorgt f\u00fcr ein harmonisches Gesamtbild.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-inner-section elementor-element elementor-element-fb5ec68 rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb5ec68\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b7a6c49 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"b7a6c49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--b7a6c49 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f236ac elementor-widget elementor-widget-image\" data-id=\"2f236ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/03\/stars.svg\" class=\"attachment-full size-full wp-image-1449717\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-76b149d\" data-id=\"76b149d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--76b149d elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fb5306 elementor-widget elementor-widget-heading\" data-id=\"6fb5306\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Deine Vorteile<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83854d3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"83854d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 Tage R\u00fcckgaberecht<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ab 50 \u20ac versandkostenfrei in DE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">sicher einkaufen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">umweltbewusste Produktion<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Individualdruck m\u00f6glich<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f039ac2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f039ac2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e4a997\" data-id=\"2e4a997\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--2e4a997 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95eafe9 elementor-widget elementor-widget-text-editor\" data-id=\"95eafe9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Flexibel einsetzbar \u2013 aufstellen oder aufh\u00e4ngen, ganz wie du magst<\/h2><p>Ob du lieber dekorierst oder klar strukturierst \u2013 das LED-Bild\/-Lampe &#8211; Geb\u00fcrsteter Stahl passt sich dir an. Du kannst es klassisch an der Wand anbringen oder ganz unkompliziert aufstellen, zum Beispiel auf einem Sideboard, einer Kommode oder Regal. Beides funktioniert ganz einfach: F\u00fcr die Wand ist die passende Aufh\u00e4ngung auf der R\u00fcckseite bereits integriert, und wenn du es frei platzierst, steht es dank seiner stabilen Bauweise sicher und stilvoll. Das integrierte Steckerkabel sorgt f\u00fcr eine einfache Stromversorgung \u2013 du brauchst lediglich eine Steckdose in der N\u00e4he. Auch in wechselnden Wohnsituationen \u2013 vom Wohnzimmer ins G\u00e4stezimmer oder vom Arbeitsplatz in den Flur \u2013 l\u00e4sst sich das Bild ganz leicht mitnehmen und neu inszenieren.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-top-section elementor-element elementor-element-c09c132 rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c09c132\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0d90e21 elementor-hidden-mobile\" data-id=\"0d90e21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--0d90e21 elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-930490b\" data-id=\"930490b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--930490b elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33d3ad5 elementor-widget elementor-widget-heading\" data-id=\"33d3ad5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sanftes Licht<br>zum Wohlf\u00fchlen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46fa6fc elementor-widget elementor-widget-heading\" data-id=\"46fa6fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">F\u00fcr entspannte Abende &amp; gem\u00fctliche Stunden<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e92a326 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e92a326\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-368ba48\" data-id=\"368ba48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--368ba48 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5b51e7 elementor-widget elementor-widget-text-editor\" data-id=\"e5b51e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Weniger Aufwand, mehr Freude \u2013 pflegeleicht, langlebig &amp; nachhaltig<\/h2><p>Das LED-Bild\/-Lampe &#8211; Geb\u00fcrsteter Stahl ist nicht nur ein optisches Highlight, sondern auch angenehm unkompliziert im Alltag. Die glatte PVC-Oberfl\u00e4che wird im UV-Direktdruckverfahren veredelt \u2013 so entstehen kr\u00e4ftige Farben, klare Konturen und eine besonders widerstandsf\u00e4hige Oberfl\u00e4che. F\u00fcr die Pflege gen\u00fcgt es, das Bild regelm\u00e4\u00dfig mit einem trockenen Tuch abzustauben. Kleinere Verschmutzungen lassen sich m\u00fchelos mit einem leicht feuchten Tuch entfernen \u2013 schnell und einfach. Auch in Sachen Nachhaltigkeit \u00fcberzeugt DEQORI: Jedes LED-Wandbild wird mit 100 % \u00d6kostrom produziert \u2013 verantwortungsbewusst, ressourcenschonend und zukunftsorientiert. So erh\u00e4ltst du ein langlebiges Produkt, das dir Tag f\u00fcr Tag Freude bereitet \u2013 f\u00fcr ein gutes Gef\u00fchl beim Kauf und beim t\u00e4glichen Anblick deines neuen Lieblingsst\u00fccks.<\/p><h2 style=\"font-size: 1em; margin-bottom: 3px;\">Lieferumfang:<\/h2><p>1x LED-Wandbild mit integrierter Beleuchtung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-f036009 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f036009\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9ca3c66 rey-colbg--classic\" data-id=\"9ca3c66\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--9ca3c66 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c029fd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c029fd5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-833169b\" data-id=\"833169b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--833169b elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1c1bbe elementor-widget elementor-widget-image\" data-id=\"b1c1bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/11\/instructions-icon.svg\" class=\"attachment-full size-full wp-image-1448531\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fa548d9\" data-id=\"fa548d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--fa548d9 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56652a3 elementor-widget elementor-widget-heading\" data-id=\"56652a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anleitung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b708423 u-last-p-margin elementor-widget elementor-widget-text-editor\" data-id=\"b708423\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tBen\u00f6tigst du Unterst\u00fctzung beim Aufbau? Kein Problem! Wirf gerne einen Blick in die Montageanleitung und Pflegehinweise.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47937f4 elementor-button-underline elementor-widget elementor-widget-button\" data-id=\"47937f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/static-imageserver.b-cdn.net\/INSTRUCTIONS\/DEQORI-LW-Instructions.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anleitung &amp; Sicherheitshinweise<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4bd1377 rey-colbg--classic\" data-id=\"4bd1377\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--4bd1377 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ad24bf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad24bf4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-900976e\" data-id=\"900976e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--900976e elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0788827 elementor-widget elementor-widget-image\" data-id=\"0788827\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/11\/info-icon.svg\" class=\"attachment-full size-full wp-image-1448527\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d94219\" data-id=\"5d94219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--5d94219 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e59aff7 elementor-widget elementor-widget-heading\" data-id=\"e59aff7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hinweis<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-200a073 u-last-p-margin elementor-widget elementor-widget-text-editor\" data-id=\"200a073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tJedes Produkt ist ein Unikat und wird, sofern nicht anders angegeben, individuell f\u00fcr dich gefertigt, wodurch h\u00f6here Lieferzeiten entstehen k\u00f6nnen. Au\u00dferdem k\u00f6nnen Farbabweichungen je nach Monitor und Endger\u00e4t auftreten, speziell bei Motiven mit nachgeahmten Materialien.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"[rey_global_section id=\"1452864\"]\n","protected":false},"featured_media":1731422,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[19,17288],"product_tag":[584,910,907,17638,17525,17527,914,1177,17526,629,922,906,632,13714,770,909,588,17528],"class_list":{"0":"post-1731420","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wandbilder-glasbilder","7":"product_cat-led-bilder","8":"product_tag-bild","9":"product_tag-blech","10":"product_tag-industriell","11":"product_tag-lampe","12":"product_tag-led-bild","13":"product_tag-led-wandbild","14":"product_tag-legierung","15":"product_tag-leichtmetall","16":"product_tag-leuchtbild","17":"product_tag-licht","18":"product_tag-material","19":"product_tag-metall","20":"product_tag-modern","21":"product_tag-motiv","22":"product_tag-struktur","23":"product_tag-textur","24":"product_tag-wanddeko","25":"product_tag-wandlampe","26":"pa_farbe-grau","27":"pa_farbe-silber","28":"pa_format-form-quadratisch","29":"pa_pid-3890","30":"pa_stil-themen-einfarbig","31":"pa_stil-themen-materialien","32":"pa_zimmer-arbeitszimmer","33":"pa_zimmer-flur-eingangsbereich","34":"fpd-variation-needed","36":"first","37":"instock","38":"sale","39":"taxable","40":"shipping-taxable","41":"purchasable","42":"product-type-variable","swatches":"rey-swatches","show_selected":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LED-Deckenleuchte geb\u00fcrsteter Stahl \u2013 Modern &amp; extra d\u00fcnn | DEQORI<\/title>\n<meta name=\"description\" content=\"Moderne LED-Deckenleuchte in geb\u00fcrstetem Stahl. Extra d\u00fcnnes Profil &amp; K\u00e4uferschutz. Jetzt bei DEQORI kaufen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LED-Deckenleuchte geb\u00fcrsteter Stahl \u2013 Modern &amp; extra d\u00fcnn | DEQORI\" \/>\n<meta property=\"og:description\" content=\"Moderne LED-Deckenleuchte in geb\u00fcrstetem Stahl. Extra d\u00fcnnes Profil &amp; K\u00e4uferschutz. Jetzt bei DEQORI kaufen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/\" \/>\n<meta property=\"og:site_name\" content=\"DEQORI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/deqorishop\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T22:39:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-LW-60-60-W-1214-UV.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/led-bilder\\\/led-bild-lampe-gebuersteter-stahl\\\/\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/led-bilder\\\/led-bild-lampe-gebuersteter-stahl\\\/\",\"name\":\"LED-Deckenleuchte geb\u00fcrsteter Stahl \u2013 Modern & extra d\u00fcnn | DEQORI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/led-bilder\\\/led-bild-lampe-gebuersteter-stahl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/led-bilder\\\/led-bild-lampe-gebuersteter-stahl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1-LW-60-60-W-1214-UV.jpg\",\"datePublished\":\"2025-09-14T02:24:02+00:00\",\"dateModified\":\"2025-10-31T22:39:50+00:00\",\"description\":\"Moderne LED-Deckenleuchte in geb\u00fcrstetem Stahl. Extra d\u00fcnnes Profil & K\u00e4uferschutz. Jetzt bei DEQORI kaufen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/led-bilder\\\/led-bild-lampe-gebuersteter-stahl\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/led-bilder\\\/led-bild-lampe-gebuersteter-stahl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/led-bilder\\\/led-bild-lampe-gebuersteter-stahl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1-LW-60-60-W-1214-UV.jpg\",\"contentUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1-LW-60-60-W-1214-UV.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/led-bilder\\\/led-bild-lampe-gebuersteter-stahl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LED-Bild\\\/-Lampe &#8211; Geb\u00fcrsteter Stahl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\",\"name\":\"DEQORI\",\"description\":\"MOTIV-ierte Wandkunst f\u00fcr deine Wohnf\u00fchloase\",\"publisher\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deqori.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#organization\",\"name\":\"DEQORI\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/deqori-logo-500px-blau-v3.png\",\"contentUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/deqori-logo-500px-blau-v3.png\",\"width\":500,\"height\":130,\"caption\":\"DEQORI\"},\"image\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/deqorishop\\\/\",\"https:\\\/\\\/www.instagram.com\\\/deqorishop\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/deqorishop\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/deqori.eu\\\/de\\\/widerruf\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"DEQORI\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LW-1214-UV\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LED-Deckenleuchte geb\u00fcrsteter Stahl \u2013 Modern & extra d\u00fcnn | DEQORI","description":"Moderne LED-Deckenleuchte in geb\u00fcrstetem Stahl. Extra d\u00fcnnes Profil & K\u00e4uferschutz. Jetzt bei DEQORI kaufen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/","og_locale":"de_DE","og_type":"article","og_title":"LED-Deckenleuchte geb\u00fcrsteter Stahl \u2013 Modern & extra d\u00fcnn | DEQORI","og_description":"Moderne LED-Deckenleuchte in geb\u00fcrstetem Stahl. Extra d\u00fcnnes Profil & K\u00e4uferschutz. Jetzt bei DEQORI kaufen!","og_url":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/","og_site_name":"DEQORI","article_publisher":"https:\/\/www.facebook.com\/deqorishop\/","article_modified_time":"2025-10-31T22:39:50+00:00","og_image":[{"url":"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-LW-60-60-W-1214-UV.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/","url":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/","name":"LED-Deckenleuchte geb\u00fcrsteter Stahl \u2013 Modern & extra d\u00fcnn | DEQORI","isPartOf":{"@id":"https:\/\/deqori.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/#primaryimage"},"image":{"@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/#primaryimage"},"thumbnailUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-LW-60-60-W-1214-UV.jpg","datePublished":"2025-09-14T02:24:02+00:00","dateModified":"2025-10-31T22:39:50+00:00","description":"Moderne LED-Deckenleuchte in geb\u00fcrstetem Stahl. Extra d\u00fcnnes Profil & K\u00e4uferschutz. Jetzt bei DEQORI kaufen!","breadcrumb":{"@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/#primaryimage","url":"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-LW-60-60-W-1214-UV.jpg","contentUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2025\/09\/1-LW-60-60-W-1214-UV.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/led-bilder\/led-bild-lampe-gebuersteter-stahl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/deqori.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/deqori.eu\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"LED-Bild\/-Lampe &#8211; Geb\u00fcrsteter Stahl"}]},{"@type":"WebSite","@id":"https:\/\/deqori.eu\/de\/#website","url":"https:\/\/deqori.eu\/de\/","name":"DEQORI","description":"MOTIV-ierte Wandkunst f\u00fcr deine Wohnf\u00fchloase","publisher":{"@id":"https:\/\/deqori.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deqori.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/deqori.eu\/de\/#organization","name":"DEQORI","url":"https:\/\/deqori.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/deqori.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/03\/deqori-logo-500px-blau-v3.png","contentUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/03\/deqori-logo-500px-blau-v3.png","width":500,"height":130,"caption":"DEQORI"},"image":{"@id":"https:\/\/deqori.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/deqorishop\/","https:\/\/www.instagram.com\/deqorishop\/","https:\/\/www.pinterest.com\/deqorishop\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/deqori.eu\/de\/widerruf\/"}}]},"product_brand":"DEQORI","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LW-1214-UV","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product\/1731420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/comments?post=1731420"}],"version-history":[{"count":0,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product\/1731420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/media\/1731422"}],"wp:attachment":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/media?parent=1731420"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_brand?post=1731420"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_cat?post=1731420"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_tag?post=1731420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}