{"id":25748,"date":"2022-06-08T17:05:53","date_gmt":"2022-06-08T17:05:53","guid":{"rendered":"https:\/\/deqori.eu\/shop\/unkategorisiert\/rosie-die-nieterin-5\/"},"modified":"2025-01-16T12:32:53","modified_gmt":"2025-01-16T12:32:53","slug":"tisch-rosie-die-nieterin","status":"publish","type":"product","link":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/","title":{"rendered":"Glastisch &#8211; Rosie die Nieterin"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6548\" class=\"elementor elementor-6548\" data-elementor-gstype=\"generic\" data-page-el-selector=\"body.elementor-page-6548\" data-disable-padding=\"\">\n\t\t\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-top-section elementor-element elementor-element-343144c rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"343144c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4137aea elementor-hidden-mobile\" data-id=\"4137aea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--4137aea elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-80ad5de\" data-id=\"80ad5de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--80ad5de elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec6f2e5 elementor-widget elementor-widget-heading\" data-id=\"ec6f2e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Beistelltisch aus Glas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fd3aa6 elementor-widget elementor-widget-heading\" data-id=\"5fd3aa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Moderne<br>\nCouchtische<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c8c47d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5c8c47d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">aus Sicherheitsglas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">schlag- &amp; kratzfest<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">einfache Montage<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-655ae10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"655ae10\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aa0ee2e rey-colbg--classic\" data-id=\"aa0ee2e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--aa0ee2e elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90dddab elementor-widget elementor-widget-image\" data-id=\"90dddab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/10\/Multi-TL-top-view-blue-white.jpg\" class=\"attachment-full size-full wp-image-1448404\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e2601bb\" data-id=\"e2601bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--e2601bb elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c72d616 elementor-widget elementor-widget-text-editor\" data-id=\"c72d616\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Mehr Platz in deinem Zuhause dank des Glastisch &#8211; Rosie die Nieterin<\/h2><p>Nach einem langen Tag willst du einfach die F\u00fc\u00dfe hochlegen, dich entspannen und nichts mehr tun. Da ist es \u00e4rgerlich, wenn du einfach keine Oberfl\u00e4che hast, wo du Kleinigkeiten, wie zum Beispiel ein Glas oder dein Smartphone, ablegen kannst. Zum Gl\u00fcck gibt es eine gro\u00dfe Auswahl an Beistelltischen, doch diese haben ein gemeinsames Problem: Sie sind h\u00e4ufig ziemlich langweilig und altbacken. M\u00f6chtest du aber den Couchtisch zum Mittelpunkt des Raums machen, entscheide dich f\u00fcr ein Modell aus Glas. Wir bieten dir moderne L\u00f6sungen f\u00fcr dein Wohnzimmer an, sodass der Blick direkt zum Tisch wandert.<\/p><h2 style=\"font-size: 1em; margin-bottom: 3px;\">Glas \u2013 Ein hochwertiges und langlebiges Material<\/h2><p>Bei Glas schwingt stets die Angst mit, dass ein falscher Handgriff direkt zu Besch\u00e4digungen f\u00fchrt. Dar\u00fcber musst du dir keine Sorgen machen, denn wir setzen auf vier Millimeter starkes Einscheibensicherheitsglas. Es ist besonders robust sowie langlebig. Insofern wird es nicht dazu kommen, dass das Glas direkt springt. Dar\u00fcber hinaus ist Glas sehr pflegeleicht. Es besteht aus einer glatten Oberfl\u00e4che, die porenfrei ist. Solltest du also irgendwas versch\u00fctten, passiert es nicht, dass die Fl\u00fcssigkeit in die Oberfl\u00e4che einzieht. Ein Wisch und schon ist der Tisch wieder auf Hochglanz poliert. Deshalb liefern wir dir direkt ein Reinigungstuch mit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-inner-section elementor-element elementor-element-382c965 rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"382c965\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07b988c elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"07b988c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--07b988c elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33fce6c elementor-widget elementor-widget-image\" data-id=\"33fce6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/03\/stars.svg\" class=\"attachment-full size-full wp-image-1449717\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e753bb\" data-id=\"1e753bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--1e753bb elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffc35a4 elementor-widget elementor-widget-heading\" data-id=\"ffc35a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Deine Vorteile<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67ace10 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"67ace10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 Tage R\u00fcckgaberecht<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ab 50 \u20ac versandkostenfrei in DE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">sicher einkaufen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">umweltbewusste Produktion<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Individualdruck m\u00f6glich<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-138a36d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"138a36d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23c8956\" data-id=\"23c8956\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--23c8956 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-740c548 elementor-widget elementor-widget-text-editor\" data-id=\"740c548\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Mit wenigen Handgriffen zum Hingucker<\/h2><p>Ein Wohnzimmer einzur\u00e4umen kann kompliziert sein, denn du musst die Balance zwischen Style und Gem\u00fctlichkeit finden. Leider muss der Style immer etwas zur\u00fcckstecken, denn in erster Linie m\u00f6chtest du dich in deinem Wohnzimmer wohlf\u00fchlen und entspannen. Doch mit einer Kleinigkeit kannst du den Style sofort wieder zur\u00fcck in deine vier W\u00e4nde holen. Die Rede ist von einem Beistelltisch aus Glas, doch es handelt sich nicht um einen klassischen Glastisch mit einer transparenten Scheibe, sondern wir bieten dir Tische mit hochwertigen Fotomotiven, wie diesem hier, an. Alternativ kannst du auch aus einer gro\u00dfen Bandbreite diverser Motive oder einem <a href=\"https:\/\/deqori.eu\/de\/kategorie\/dein-foto\/?product-cato=357\">eigenen Foto<\/a> w\u00e4hlen, wobei sie alle eins gemeinsam haben: eine hohe Qualit\u00e4t. Wir setzen auf hoch entwickelte Produktionsverfahren, damit die Farben besonders kr\u00e4ftig und kontrastreich sind. Gleicherma\u00dfen entsteht durch die Glasscheibe ein ansehnlicher 3D-Farbtiefeneffekt, welcher den Glastisch &#8211; Rosie die Nieterin umso beeindruckender macht. Insofern ist er nicht einfach ein Tisch, um etwas abzustellen, sondern ein Designobjekt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-top-section elementor-element elementor-element-9680f96 rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9680f96\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ffbee07 elementor-hidden-mobile\" data-id=\"ffbee07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--ffbee07 elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-856659d\" data-id=\"856659d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--856659d elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67517c3 elementor-widget elementor-widget-heading\" data-id=\"67517c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Abgestimmt auf<br>jeden Raum<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36814fa elementor-widget elementor-widget-heading\" data-id=\"36814fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">In vielseitigen Gr\u00f6\u00dfen und <br>\nklassische Farben.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68f310f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68f310f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec97674\" data-id=\"ec97674\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--ec97674 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c3bf1d elementor-widget elementor-widget-text-editor\" data-id=\"6c3bf1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Ein stabiles Gestell<\/h2><p>Sicherlich spielt die Glasplatte mit Motiv die gr\u00f6\u00dfte Rolle, doch auch das Gestell darfst du nicht vernachl\u00e4ssigen. Wir setzen auf ein Gestell aus 100 Prozent recycelten Hartfasern. Jene sind sehr stabil und gleichzeitig tust du der Umwelt etwas Gutes. Generell achten wir auf eine hohe Umweltfreundlichkeit, denn wir produzieren unsere Waren klimaneutral und mit \u00d6kostrom. Neben den Hartfasern setzen wir auf ein schwarzes oder wei\u00dfes Acryl-Finish, um f\u00fcr mehr Haltbarkeit zu sorgen. Grunds\u00e4tzlich kannst du dich zwischen zwei Gr\u00f6\u00dfen entscheiden: 55 x 55 Zentimeter oder 90 x 50 Zentimeter. Somit kann der Tisch sowohl vor der Couch als auch an einem anderen Platz in deiner Wohnung stehen. Ob es zu Problemen mit deinem bisherigen Stil kommt? Auf keinen Fall, denn der Beistelltisch aus Glas kann deinen Style erg\u00e4nzen oder f\u00fcr einen Stilbruch sorgen. Glas ist sehr modern und f\u00fcgt sich somit hervorragend in neumodische Umgebungen ein. Willst du aber, dass der Glastisch &#8211; Rosie die Nieterin sofort ins Auge f\u00e4llt, dann ist der Stilbruch das Richtige f\u00fcr dich. Au\u00dferdem kannst du anhand des Bildes ebenfalls deinen Stil miteinflie\u00dfen lassen.<\/p><h2 style=\"font-size: 1em; margin-bottom: 3px;\">Lieferumfang:<\/h2><p>1x Couchtisch inklusive Reinigungstuch<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-bcde465 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bcde465\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51a44e2 rey-colbg--classic\" data-id=\"51a44e2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--51a44e2 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e6a8541 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6a8541\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b96edb\" data-id=\"6b96edb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--6b96edb elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dce7aea elementor-widget elementor-widget-image\" data-id=\"dce7aea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/11\/instructions-icon.svg\" class=\"attachment-full size-full wp-image-1448531\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-121dc83\" data-id=\"121dc83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--121dc83 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3fbfed elementor-widget elementor-widget-heading\" data-id=\"f3fbfed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anleitung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfbaa6b u-last-p-margin elementor-widget elementor-widget-text-editor\" data-id=\"bfbaa6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tBen\u00f6tigst du Unterst\u00fctzung beim Aufbau? Kein Problem! Wirf gerne einen Blick in die Montageanleitung und Pflegehinweise.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a94704 elementor-button-underline elementor-widget elementor-widget-button\" data-id=\"6a94704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/static-imageserver.b-cdn.net\/INSTRUCTIONS\/DEQORI-TL-Instructions.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anleitung &amp; Sicherheitshinweise<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a4983f rey-colbg--classic\" data-id=\"2a4983f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--2a4983f elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a588a7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a588a7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-749183f\" data-id=\"749183f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--749183f elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02c5c3a elementor-widget elementor-widget-image\" data-id=\"02c5c3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/11\/info-icon.svg\" class=\"attachment-full size-full wp-image-1448527\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-03f4f2e\" data-id=\"03f4f2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--03f4f2e elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b021c3 elementor-widget elementor-widget-heading\" data-id=\"1b021c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hinweis<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e03f6df u-last-p-margin elementor-widget elementor-widget-text-editor\" data-id=\"e03f6df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tJedes Produkt ist ein Unikat und wird, sofern nicht anders angegeben, individuell f\u00fcr dich gefertigt, wodurch h\u00f6here Lieferzeiten entstehen k\u00f6nnen. Au\u00dferdem k\u00f6nnen Farbabweichungen je nach Monitor und Endger\u00e4t auftreten, speziell bei Motiven mit nachgeahmten Materialien.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"[rey_global_section id=\"6224\"]\n","protected":false},"featured_media":135036,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[42],"product_tag":[2368,1520,652,653,374,2365,2366,585,651,2369,997,2364,2367],"class_list":["post-25748","product","type-product","status-publish","has-post-thumbnail","product_cat-glastisch","product_tag-2368","product_tag-amerika","product_tag-beistelltisch","product_tag-couch","product_tag-couchtisch","product_tag-frauen","product_tag-frauenpower","product_tag-glas","product_tag-glastisch","product_tag-propaganda","product_tag-vintage","product_tag-we-can-do-it","product_tag-ww2","pa_farbe-blau","pa_farbe-gelb","pa_format-form-quadratisch","pa_groesse-55x55-cm","pa_groesse-90x55-cm","pa_pid-4272","pa_stil-themen-illustrationen","pa_stil-themen-menschen","pa_stil-themen-sprueche-zitate","pa_zimmer-arbeitszimmer","pa_zimmer-badezimmer","pa_zimmer-kueche-esszimmer","fpd-variation-needed","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","rey-swatches",""],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rosie die Nieterin Glastisch Schlafzimmer - DEQORI | Spr\u00fcche &amp; Zitate<\/title>\n<meta name=\"description\" content=\"Erkunden Sie unser Sortiment an Schlafzimmertischen. Der Glastisch &#039;Rosie die Nieterin&#039; hat eine 4mm dicke Glasplatte. Gro\u00dfe Auswahl nur bei DEQORI!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rosie die Nieterin Glastisch Schlafzimmer - DEQORI | Spr\u00fcche &amp; Zitate\" \/>\n<meta property=\"og:description\" content=\"Erkunden Sie unser Sortiment an Schlafzimmertischen. Der Glastisch &#039;Rosie die Nieterin&#039; hat eine 4mm dicke Glasplatte. Gro\u00dfe Auswahl nur bei DEQORI!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/\" \/>\n<meta property=\"og:site_name\" content=\"DEQORI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/deqorishop\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T12:32:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/06\/1-TL-55-55-B-2371.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/glastisch\\\/tisch-rosie-die-nieterin\\\/\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/glastisch\\\/tisch-rosie-die-nieterin\\\/\",\"name\":\"Rosie die Nieterin Glastisch Schlafzimmer - DEQORI | Spr\u00fcche &amp; Zitate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/glastisch\\\/tisch-rosie-die-nieterin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/glastisch\\\/tisch-rosie-die-nieterin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/1-TL-55-55-B-2371.jpg\",\"datePublished\":\"2022-06-08T17:05:53+00:00\",\"dateModified\":\"2025-01-16T12:32:53+00:00\",\"description\":\"Erkunden Sie unser Sortiment an Schlafzimmertischen. Der Glastisch 'Rosie die Nieterin' hat eine 4mm dicke Glasplatte. Gro\u00dfe Auswahl nur bei DEQORI!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/glastisch\\\/tisch-rosie-die-nieterin\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/glastisch\\\/tisch-rosie-die-nieterin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/glastisch\\\/tisch-rosie-die-nieterin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/1-TL-55-55-B-2371.jpg\",\"contentUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/1-TL-55-55-B-2371.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/glastisch\\\/tisch-rosie-die-nieterin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Glastisch &#8211; Rosie die Nieterin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\",\"name\":\"DEQORI\",\"description\":\"MOTIV-ierte Wandkunst f\u00fcr deine Wohnf\u00fchloase\",\"publisher\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deqori.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#organization\",\"name\":\"DEQORI\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/deqori-logo-500px-blau-v3.png\",\"contentUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/deqori-logo-500px-blau-v3.png\",\"width\":500,\"height\":130,\"caption\":\"DEQORI\"},\"image\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/deqorishop\\\/\",\"https:\\\/\\\/www.instagram.com\\\/deqorishop\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/deqorishop\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/deqori.eu\\\/de\\\/widerruf\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"DEQORI\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rosie die Nieterin Glastisch Schlafzimmer - DEQORI | Spr\u00fcche &amp; Zitate","description":"Erkunden Sie unser Sortiment an Schlafzimmertischen. Der Glastisch 'Rosie die Nieterin' hat eine 4mm dicke Glasplatte. Gro\u00dfe Auswahl nur bei DEQORI!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/","og_locale":"de_DE","og_type":"article","og_title":"Rosie die Nieterin Glastisch Schlafzimmer - DEQORI | Spr\u00fcche &amp; Zitate","og_description":"Erkunden Sie unser Sortiment an Schlafzimmertischen. Der Glastisch 'Rosie die Nieterin' hat eine 4mm dicke Glasplatte. Gro\u00dfe Auswahl nur bei DEQORI!","og_url":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/","og_site_name":"DEQORI","article_publisher":"https:\/\/www.facebook.com\/deqorishop\/","article_modified_time":"2025-01-16T12:32:53+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/06\/1-TL-55-55-B-2371.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/","url":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/","name":"Rosie die Nieterin Glastisch Schlafzimmer - DEQORI | Spr\u00fcche &amp; Zitate","isPartOf":{"@id":"https:\/\/deqori.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/#primaryimage"},"image":{"@id":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/#primaryimage"},"thumbnailUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/06\/1-TL-55-55-B-2371.jpg","datePublished":"2022-06-08T17:05:53+00:00","dateModified":"2025-01-16T12:32:53+00:00","description":"Erkunden Sie unser Sortiment an Schlafzimmertischen. Der Glastisch 'Rosie die Nieterin' hat eine 4mm dicke Glasplatte. Gro\u00dfe Auswahl nur bei DEQORI!","breadcrumb":{"@id":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/#primaryimage","url":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/06\/1-TL-55-55-B-2371.jpg","contentUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/06\/1-TL-55-55-B-2371.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/deqori.eu\/de\/shop\/glastisch\/tisch-rosie-die-nieterin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/deqori.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/deqori.eu\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Glastisch &#8211; Rosie die Nieterin"}]},{"@type":"WebSite","@id":"https:\/\/deqori.eu\/de\/#website","url":"https:\/\/deqori.eu\/de\/","name":"DEQORI","description":"MOTIV-ierte Wandkunst f\u00fcr deine Wohnf\u00fchloase","publisher":{"@id":"https:\/\/deqori.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deqori.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/deqori.eu\/de\/#organization","name":"DEQORI","url":"https:\/\/deqori.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/deqori.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/03\/deqori-logo-500px-blau-v3.png","contentUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/03\/deqori-logo-500px-blau-v3.png","width":500,"height":130,"caption":"DEQORI"},"image":{"@id":"https:\/\/deqori.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/deqorishop\/","https:\/\/www.instagram.com\/deqorishop\/","https:\/\/www.pinterest.com\/deqorishop\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/deqori.eu\/de\/widerruf\/"}}]},"product_brand":"DEQORI","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product\/25748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/comments?post=25748"}],"version-history":[{"count":0,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product\/25748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/media\/135036"}],"wp:attachment":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/media?parent=25748"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_brand?post=25748"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_cat?post=25748"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_tag?post=25748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}