{"id":577381,"date":"2024-07-03T21:48:20","date_gmt":"2024-07-03T21:48:20","guid":{"rendered":"https:\/\/deqori.eu\/?post_type=product&#038;p=577381"},"modified":"2026-05-14T09:29:22","modified_gmt":"2026-05-14T09:29:22","slug":"wandbild-koenigliches-antlitz","status":"publish","type":"product","link":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/","title":{"rendered":"Wandbild &#8211; K\u00f6nigliches Antlitz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4695\" class=\"elementor elementor-4695\" data-elementor-gstype=\"generic\" data-page-el-selector=\"body.elementor-page-4695\" data-disable-padding=\"\">\n\t\t\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-top-section elementor-element elementor-element-8f2edd7 rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f2edd7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ba45da elementor-hidden-mobile\" data-id=\"2ba45da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--2ba45da elementor-widget-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a0b2480\" data-id=\"a0b2480\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--a0b2480 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-520fedb elementor-widget elementor-widget-heading\" data-id=\"520fedb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Einteiliges Glasbild<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c698fa6 elementor-widget elementor-widget-heading\" data-id=\"c698fa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eleganz &amp; Glanz<br>\naus Acryl &amp; Glas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d29f1d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7d29f1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acryl- oder Echtglas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">einfache Montage<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">viele Designs<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e61333d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e61333d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-71671fc rey-colbg--classic\" data-id=\"71671fc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--71671fc elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf32085 elementor-widget elementor-widget-image\" data-id=\"bf32085\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/10\/Multi-WA-C-top-view-blue-white.jpg\" class=\"attachment-full size-full wp-image-1448406\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cc10a20\" data-id=\"cc10a20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--cc10a20 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de79c75 elementor-widget elementor-widget-text-editor\" data-id=\"de79c75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Einteiliges Wandbild &#8211; K\u00f6nigliches Antlitz aus Glas \u2013 Ein Hingucker in jedem Raum<\/h2><p>Ein Bild perfekt in Szene zu setzen, ist ein Leichtes, wenn du dich f\u00fcr ein Wandbild aus Glas entscheidest. Das Foto befindet sich hinter Glas und f\u00e4llt somit direkt ins Auge, ist aber gleicherma\u00dfen gut gesch\u00fctzt. Nat\u00fcrlich hast du zahlreiche Gestaltungsm\u00f6glichkeiten, doch du solltest dich zuerst den etlichen Vorteilen annehmen. Immerhin ist ein einteiliges Wandbild aus Glas ein Hingucker und unverzichtbar f\u00fcr eine stylische Wohnung.<\/p><h2 style=\"font-size: 1em; margin-bottom: 3px;\">Woraus besteht das Wandbild?<\/h2><p>Das Material spielt die gr\u00f6\u00dfte Rolle, denn jenes sorgt f\u00fcr den einmaligen Look. Du kannst dich zwischen vier Millimeter dickem <a href=\"https:\/\/deqori.eu\/de\/hilfe-faq\/\">Einscheibensicherheitsglas oder Acryl (PMMA)<\/a> entscheiden. Beide Arten sorgen daf\u00fcr, dass das Bild hinter der Scheibe gesch\u00fctzt ist. Gleicherma\u00dfen wurde auf jeglichen Rahmen verzichtet, um das Bild in den Vordergrund zu r\u00fccken. Nat\u00fcrlich achten wir auf eine hochwertige und klimaneutrale Herstellung. Deshalb werden alle Bilder mit 100 Prozent \u00d6kostrom gefertigt, sodass du nicht nur ein eindrucksvolles Wandbild erh\u00e4ltst, sondern zugleich guten Gewissens dessen Sch\u00f6nheit genie\u00dfen kannst.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-inner-section elementor-element elementor-element-738091a rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"738091a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-403ad47 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"403ad47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--403ad47 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e0cff9 elementor-widget elementor-widget-image\" data-id=\"6e0cff9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/03\/stars.svg\" class=\"attachment-full size-full wp-image-1449717\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ae2264f\" data-id=\"ae2264f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--ae2264f elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eadaa5a elementor-widget elementor-widget-heading\" data-id=\"eadaa5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Deine Vorteile<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f3975b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9f3975b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 Tage R\u00fcckgaberecht<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ab 50 \u20ac versandkostenfrei in DE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">sicher einkaufen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">umweltbewusste Produktion<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 128 128\" style=\"enable-background:new 0 0 128 128;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M85.3,46.5L54.5,77.3L42.8,65.6c-0.8-0.8-2-0.8-2.8,0c-0.8,0.8-0.8,2,0,2.8l14.5,14.5l33.6-33.6c0.8-0.8,0.8-2,0-2.8   C87.3,45.7,86,45.7,85.3,46.5z M64,13.9c-27.6,0-50.1,22.5-50.1,50.1c0,27.6,22.5,50.1,50.1,50.1h0c27.6,0,50.1-22.5,50.1-50.1   C114.2,36.4,91.7,13.9,64,13.9z M64,110.1L64,110.1c-25.4,0-46.1-20.7-46.1-46.1c0-25.4,20.7-46.1,46.1-46.1s46.1,20.7,46.1,46.1   C110.2,89.4,89.5,110.1,64,110.1z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Individualdruck m\u00f6glich<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9911474 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9911474\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c020fae\" data-id=\"c020fae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--c020fae elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1529b3 elementor-widget elementor-widget-text-editor\" data-id=\"c1529b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Warum Glas? Das sind die Vorteile des Materials<\/h2><p>Es gibt viele M\u00f6glichkeiten, wie du ein Wandbild in Szene setzen kannst. Glas bietet aber zahlreiche Vorteile, angefangen bei der Sicherheit. Grunds\u00e4tzlich kannst du das Wandbild &#8211; K\u00f6nigliches Antlitz aus Glas \u00fcberall aufh\u00e4ngen, auch in R\u00e4umen mit hoher Luftfeuchtigkeit, wie der K\u00fcche oder dem Badezimmer. Das Bild ist hinter dem Glas eingelassen und es passiert somit nicht, dass Wasser eindringt. Gerade im Vergleich zu einem klassischen Poster bist du wesentlich flexibler. Sollte es einmal passiert sein, dass etwas Feuchtigkeit auf die Scheibe gespritzt oder getropft ist, kannst du jene einfach abwischen. Das Bild und dessen Farben werden davon nicht beeinflusst. Ein weiterer Vorteil ist die Langlebigkeit. Echt- sowie Acrylglas sind sehr hochwertige und robuste Materialien. Du musst also keine Angst haben, dass ein falscher Handgriff direkt zu Kratzern oder Spr\u00fcngen f\u00fchrt. Stattdessen h\u00e4lt das Wandbild aus Glas viel aus und wird auch einen oder mehrere Umz\u00fcge ohne Probleme \u00fcberstehen.<\/p><h2 style=\"font-size: 1em; margin-bottom: 3px;\">Ein Blick auf die R\u00fcckseite<\/h2><p>Es ist nicht \u00fcberraschend, dass du deinen Blick nicht vom Wandbild &#8211; K\u00f6nigliches Antlitz abwenden kannst, doch schau dir ebenso die R\u00fcckseite an. Hier findest du eine bereits vormontierte Wandhalterung. Nachdem du also die Dekoration ausgepackt hast, kann sie sofort an die Wand gebracht werden. Du musst dich nicht mit umst\u00e4ndlichen Befestigungsmethoden besch\u00e4ftigen. Zus\u00e4tzlich setzen wir auf Abstandshalter, die sich auf der R\u00fcckseite befinden. Dadurch steht das Bild einige Millimeter von der Wand ab, was zu einem eindrucksvollen Schwebeeffekt f\u00fchrt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"rey-lazyBg elementor-section elementor-top-section elementor-element elementor-element-4591991 rey-section-bg--classic elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4591991\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da95e32 elementor-hidden-mobile\" data-id=\"da95e32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--da95e32 elementor-widget-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38f5534\" data-id=\"38f5534\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--38f5534 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97b54ce elementor-widget elementor-widget-heading\" data-id=\"97b54ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Von gro\u00df<br>bis klein<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9fa02a elementor-widget elementor-widget-heading\" data-id=\"f9fa02a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vielseitige Gr\u00f6\u00dfen<br>f\u00fcr jeden Bedarf!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e3f86c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e3f86c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce4b1ea\" data-id=\"ce4b1ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--ce4b1ea elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2caee5d elementor-widget elementor-widget-text-editor\" data-id=\"2caee5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Die beste Qualit\u00e4t f\u00fcr deine Bilder<\/h2>\n<p>Ein Foto in Glas ist modern und \u00fcberzeugt durch sein hochwertiges Design, doch am Ende des Tages entscheidest du, welches Bild dir hinter dem Glas entgegenstrahlt. Wir bieten dir eine eindrucksvolle Auswahl an bereits vorgefertigten Motiven wie dem Wandbild &#8211; K\u00f6nigliches Antlitz. Dabei achten wir auf h\u00f6chste Qualit\u00e4t und sichern dir einmalig sch\u00f6ne Aufnahmen, die in jedes Zimmer passen. Selbstverst\u00e4ndlich kannst du dich auch daf\u00fcr entscheiden, ein <a href=\"https:\/\/deqori.eu\/de\/kategorie\/dein-foto\/?product-cato=350&amp;attro-format-form=114,118,115,117,116\">eigenes Foto<\/a> zu verewigen. Wir bieten dir ein hoch entwickeltes Produktionsverfahren an. Dank der Nanotechnologie wird jedes Bild gestochen scharf aufs Papier gebracht. Dadurch entsteht eine hochaufl\u00f6sende Farbqualit\u00e4t. Ein H\u00f6hepunkt ist aber der eindrucksvolle 3D-Farbtiefeneffekt. Somit ist es nicht einfach Wanddeko, sondern das Highlight im Raum.<\/p>\n<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Entscheide dich f\u00fcr ein Wandbild aus Glas!<\/h2>\n<p>Ein Wandbild aus Glas bringt viele unterschiedliche Vorteile mit, wobei das Echt- oder Acrylglas sich besonders hervortun. Wir setzen auf eine hochwertige Qualit\u00e4t sowie eine Dicke von vier Millimetern. Dein Bild kommt bruchsicher verpackt bei dir an und dank der vormontierten Wandhalterung findet es direkt seinen vorbestimmten Platz. Dar\u00fcber hinaus achten wir auf h\u00f6chste Fotoqualit\u00e4t. Die Farben wirken lebensecht und ebenso besteht ein beeindruckender 3D-Farbtiefeneffekt. Dadurch passt das Bild zu jedem Einrichtungsstil und setzt gekonnt Akzente, ohne den urspr\u00fcnglichen Stil zu \u00fcberlagern.<\/p>\n<h2 style=\"font-size: 1em; margin-bottom: 3px;\">Lieferumfang:<\/h2>\n<p>1x Einteiliges Glasbild<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-a2fb8ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2fb8ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4f7c4b1 rey-colbg--classic\" data-id=\"4f7c4b1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--4f7c4b1 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4d08874 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d08874\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41029e8\" data-id=\"41029e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--41029e8 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a4c5f2 elementor-widget elementor-widget-image\" data-id=\"9a4c5f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/11\/instructions-icon.svg\" class=\"attachment-full size-full wp-image-1448531\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ce2ebe2\" data-id=\"ce2ebe2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--ce2ebe2 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df648f1 elementor-widget elementor-widget-heading\" data-id=\"df648f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anleitungen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffe0d5d u-last-p-margin elementor-widget elementor-widget-text-editor\" data-id=\"ffe0d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tBen\u00f6tigst du Unterst\u00fctzung beim Aufbau? Kein Problem! Wirf gerne einen Blick in die Montageanleitung und Pflegehinweise.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c66d95c elementor-button-underline elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"c66d95c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/static-imageserver.b-cdn.net\/INSTRUCTIONS\/DEQORI-WA-G-Instructions.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anleitung (Echtglas)<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64e264b elementor-button-underline elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"64e264b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/static-imageserver.b-cdn.net\/INSTRUCTIONS\/DEQORI-WA-A-Instructions.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Anleitung (Acryl)<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"rey-lazyBg elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5265c1e rey-colbg--classic\" data-id=\"5265c1e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap--5265c1e elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6d8a5cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d8a5cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d92a48\" data-id=\"7d92a48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--7d92a48 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35ef284 elementor-widget elementor-widget-image\" data-id=\"35ef284\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/11\/info-icon.svg\" class=\"attachment-full size-full wp-image-1448527\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0f154c8\" data-id=\"0f154c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap--0f154c8 elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b36c2c elementor-widget elementor-widget-heading\" data-id=\"5b36c2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hinweis<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92ce718 u-last-p-margin elementor-widget elementor-widget-text-editor\" data-id=\"92ce718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tJedes Produkt ist ein Unikat und wird, sofern nicht anders angegeben, individuell f\u00fcr dich gefertigt, wodurch h\u00f6here Lieferzeiten entstehen k\u00f6nnen. Au\u00dferdem k\u00f6nnen Farbabweichungen je nach Monitor und Endger\u00e4t auftreten, speziell bei Motiven mit nachgeahmten Materialien.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"[rey_global_section id=\"2307\"]\n","protected":false},"featured_media":1057510,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[19,4870],"product_tag":[6792,584,623,585,586,678,3523,7271,7274,74,5297,1253,7272,4983,7273,809,587,588,589,849],"class_list":["post-577381","product","type-product","status-publish","has-post-thumbnail","product_cat-wandbilder-glasbilder","product_cat-acrylglas-echtglas","product_tag-afrikanische-savanne","product_tag-bild","product_tag-design","product_tag-glas","product_tag-glasbild","product_tag-kunst","product_tag-lebensraum","product_tag-loewenbild","product_tag-mut","product_tag-natur","product_tag-naturschoenheit","product_tag-raubtier","product_tag-raumdekoration","product_tag-schwarz-weiss-fotografie","product_tag-staerke","product_tag-tierfotografie","product_tag-wandbild","product_tag-wanddeko","product_tag-wildnis","product_tag-wildtier","pa_farbe-schwarz-weiss","pa_format-form-1-teilig","pa_format-form-quadratisch","pa_pid-7270","pa_stil-themen-tiere","pa_zimmer-arbeitszimmer","pa_zimmer-flur-eingangsbereich","pa_zimmer-schlafzimmer","pa_zimmer-wohnzimmer","cha-variation-needed","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-product-safety-information","rey-swatches",""],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modernes Glasbild &#039;K\u00f6nigliches Antlitz&#039; \u2013 DEQORI<\/title>\n<meta name=\"description\" content=\"Entdecken Sie das moderne Glasbild K\u00f6nigliches Antlitz in brillanter Farbqualit\u00e4t. \u00dcber 4.000 Motive verf\u00fcgbar! Jetzt im DEQORI-Shop kaufen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modernes Glasbild &#039;K\u00f6nigliches Antlitz&#039; \u2013 DEQORI\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie das moderne Glasbild K\u00f6nigliches Antlitz in brillanter Farbqualit\u00e4t. \u00dcber 4.000 Motive verf\u00fcgbar! Jetzt im DEQORI-Shop kaufen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/\" \/>\n<meta property=\"og:site_name\" content=\"DEQORI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/deqorishop\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T09:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/07\/1-WA-S-30-30-G-2848.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/wandbild-koenigliches-antlitz\\\/\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/wandbild-koenigliches-antlitz\\\/\",\"name\":\"Modernes Glasbild 'K\u00f6nigliches Antlitz' \u2013 DEQORI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/wandbild-koenigliches-antlitz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/wandbild-koenigliches-antlitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1-WA-S-30-30-G-2848.jpg\",\"datePublished\":\"2024-07-03T21:48:20+00:00\",\"dateModified\":\"2026-05-14T09:29:22+00:00\",\"description\":\"Entdecken Sie das moderne Glasbild K\u00f6nigliches Antlitz in brillanter Farbqualit\u00e4t. \u00dcber 4.000 Motive verf\u00fcgbar! Jetzt im DEQORI-Shop kaufen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/wandbild-koenigliches-antlitz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/wandbild-koenigliches-antlitz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/wandbild-koenigliches-antlitz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1-WA-S-30-30-G-2848.jpg\",\"contentUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1-WA-S-30-30-G-2848.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/wandbilder-glasbilder\\\/wandbild-koenigliches-antlitz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/deqori.eu\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wandbild &#8211; K\u00f6nigliches Antlitz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\",\"name\":\"DEQORI\",\"description\":\"MOTIV-ierte Wandkunst f\u00fcr deine Wohnf\u00fchloase\",\"publisher\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deqori.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#organization\",\"name\":\"DEQORI\",\"url\":\"https:\\\/\\\/deqori.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/deqori-logo-500px-blau-v3.png\",\"contentUrl\":\"https:\\\/\\\/deqori.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/deqori-logo-500px-blau-v3.png\",\"width\":500,\"height\":130,\"caption\":\"DEQORI\"},\"image\":{\"@id\":\"https:\\\/\\\/deqori.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/deqorishop\\\/\",\"https:\\\/\\\/www.instagram.com\\\/deqorishop\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/deqorishop\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/deqori.eu\\\/de\\\/widerruf\\\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"DEQORI\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modernes Glasbild 'K\u00f6nigliches Antlitz' \u2013 DEQORI","description":"Entdecken Sie das moderne Glasbild K\u00f6nigliches Antlitz in brillanter Farbqualit\u00e4t. \u00dcber 4.000 Motive verf\u00fcgbar! Jetzt im DEQORI-Shop kaufen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/","og_locale":"de_DE","og_type":"article","og_title":"Modernes Glasbild 'K\u00f6nigliches Antlitz' \u2013 DEQORI","og_description":"Entdecken Sie das moderne Glasbild K\u00f6nigliches Antlitz in brillanter Farbqualit\u00e4t. \u00dcber 4.000 Motive verf\u00fcgbar! Jetzt im DEQORI-Shop kaufen.","og_url":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/","og_site_name":"DEQORI","article_publisher":"https:\/\/www.facebook.com\/deqorishop\/","article_modified_time":"2026-05-14T09:29:22+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/07\/1-WA-S-30-30-G-2848.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/","url":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/","name":"Modernes Glasbild 'K\u00f6nigliches Antlitz' \u2013 DEQORI","isPartOf":{"@id":"https:\/\/deqori.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/#primaryimage"},"image":{"@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/#primaryimage"},"thumbnailUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/07\/1-WA-S-30-30-G-2848.jpg","datePublished":"2024-07-03T21:48:20+00:00","dateModified":"2026-05-14T09:29:22+00:00","description":"Entdecken Sie das moderne Glasbild K\u00f6nigliches Antlitz in brillanter Farbqualit\u00e4t. \u00dcber 4.000 Motive verf\u00fcgbar! Jetzt im DEQORI-Shop kaufen.","breadcrumb":{"@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/#primaryimage","url":"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/07\/1-WA-S-30-30-G-2848.jpg","contentUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2024\/07\/1-WA-S-30-30-G-2848.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/deqori.eu\/de\/shop\/wandbilder-glasbilder\/wandbild-koenigliches-antlitz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/deqori.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/deqori.eu\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Wandbild &#8211; K\u00f6nigliches Antlitz"}]},{"@type":"WebSite","@id":"https:\/\/deqori.eu\/de\/#website","url":"https:\/\/deqori.eu\/de\/","name":"DEQORI","description":"MOTIV-ierte Wandkunst f\u00fcr deine Wohnf\u00fchloase","publisher":{"@id":"https:\/\/deqori.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deqori.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/deqori.eu\/de\/#organization","name":"DEQORI","url":"https:\/\/deqori.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/deqori.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/03\/deqori-logo-500px-blau-v3.png","contentUrl":"https:\/\/deqori.eu\/wp-content\/uploads\/2022\/03\/deqori-logo-500px-blau-v3.png","width":500,"height":130,"caption":"DEQORI"},"image":{"@id":"https:\/\/deqori.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/deqorishop\/","https:\/\/www.instagram.com\/deqorishop\/","https:\/\/www.pinterest.com\/deqorishop\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/deqori.eu\/de\/widerruf\/"}}]},"product_brand":"DEQORI","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product\/577381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/comments?post=577381"}],"version-history":[{"count":0,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product\/577381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/media\/1057510"}],"wp:attachment":[{"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/media?parent=577381"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_brand?post=577381"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_cat?post=577381"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/deqori.eu\/de\/wp-json\/wp\/v2\/product_tag?post=577381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}